{"id":7307,"date":"2022-07-21T09:02:00","date_gmt":"2022-07-21T14:02:00","guid":{"rendered":"http:\/\/infosol.com.mx\/wordpress\/?p=7307"},"modified":"2025-07-07T14:49:20","modified_gmt":"2025-07-07T20:49:20","slug":"3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp","status":"publish","type":"post","link":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/","title":{"rendered":"3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP"},"content":{"rendered":"<p>No es un secreto que la mayor\u00eda de nosotros somos usuarios en alguna red social, ya sea por trabajo o entretenimiento hemos tenido la necesidad de crear alguna cuenta. Seg\u00fan el \u00faltimo estudio de HubSpot, sobre redes sociales, 4200 millones de personas son usuarios de alguna red social, as\u00ed que probablemente un porcentaje considerable de empleados en tu empresa posean alguna cuenta en estas plataformas. Pero\u2026 \u00bfc\u00f3mo afecta o beneficia esto a la\u00a0<a href=\"https:\/\/infosol.com.mx\/wordpress\/8-importantes-beneficios-que-las-relaciones-publicas-aportan-a-las-organizaciones\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>estrategia de relaciones p\u00fablicas<\/strong><\/a>\u00a0de tu organizaci\u00f3n?<\/p>\n<p><!-- \/wp:post-content --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Basta con revisar las redes sociales y, en particular, el caso de \u00e9xito de una reconocida marca estadounidense de donas, que se convirti\u00f3 en tendencia gracias a que una de sus empleadas compart\u00eda fotos y videos casuales, no confidenciales de su trabajo, en sus redes personales. Fue tal el \u00e9xito, que el contenido logr\u00f3 +4.2M de vistas, 642.3 mil\u00a0<em>likes\u00a0<\/em>y, adem\u00e1s, conversaciones positivas de los usuarios hacia la marca, reflejados en +3.7K comentarios.\u00a0<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Esto significa que el contenido creado por los colaboradores de las marcas tiene el potencial de ser viral y convertirse en tendencia, lo que puede ayudar a impulsar la estrategia de RP de las empresas.\u00a0<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Para ahondar m\u00e1s en el tema, comencemos por se\u00f1alar que el contenido generado por empleados es, como su nombre lo indica, aquel contenido que habla sobre una marca y que proviene de la creatividad de tus empleados. Estos recursos pueden presentarse en diferentes formatos (Tiktoks, Reels de Instagram o fotos y videos en Facebook<em>\u00a0<\/em>publicados en las redes sociales de los colaboradores) y se convierten en material que promueve la imagen e identidad de tu marca a trav\u00e9s de la perspectiva amplificada de un tercero, que tiene relaci\u00f3n directa y continua con ella.\u00a0<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>La forma en la que tus empleados se expresan y demuestran su experiencia con tu marca, a trav\u00e9s de los contenidos en sus redes, tiene un amplio potencial que va desde humanizarla hasta prever situaciones de crisis contra la misma. Es vital tener presente su existencia, ya que muchos relatan, a viva voz, la experiencia con la marca y expresan c\u00f3mo son sus instalaciones, sus procesos de capacitaci\u00f3n, las personas y valores con las que trabajan, el ambiente laboral, c\u00f3mo los acompa\u00f1a la empresa ante una adversidad, el trato al cliente y la calidad en el servicio y\/o productos.\u00a0<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Como puedes darte cuenta, son muchos los \u00e1mbitos que involucra el contenido creado por tu equipo, es por ello que aqu\u00ed te menciono 3 de las principales razones para impulsarlo:<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading --><\/p>\n<h4>1. Evoluci\u00f3n en la cultura organizacional<\/h4>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Una caracter\u00edstica de la evoluci\u00f3n laboral, es que mediante el contenido generado por empleados, ellos puedan sentirse motivados y comprometidos con la organizaci\u00f3n, mediante la voz que se les d\u00e9 en la empresa. El compartir en sus redes un fragmento de sus actividades cotidianas en el trabajo, puede brindarles visibilidad y reconocimiento ante sus gerentes, auto empoderamiento y liderazgo intelectual ante su c\u00edrculo cercano, por sus logros y actividades profesionales.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading --><\/p>\n<h4>2. Incrementa las ventas y confianza en tu marca<\/h4>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Seg\u00fan el\u00a0User Generated Content\u00a02022, el contenido generado por empleados es m\u00e1s visto y genera m\u00e1s compromiso, ya que las cuentas personales poseen 10 veces m\u00e1s seguidores y 8 veces m\u00e1s participaci\u00f3n que las cuentas de empresas;<em>\u00a0<\/em>es por ello que la libertad creativa y entusiasmo que promuevan tus colaboradores, a trav\u00e9s de su contenido, puede generar mayor credibilidad ante la visi\u00f3n de tu marca y generar una motivaci\u00f3n en tu audiencia para comprar tus productos y\/o servicios.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:heading --><\/p>\n<h4>3. Reclutamientos efectivos\u00a0<\/h4>\n<p><!-- \/wp:heading --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Cuando un colaborador se encuentra motivado en su organizaci\u00f3n y lo comparte, da pauta a que muchos posibles candidatos efectivos vean esa publicaci\u00f3n y se cuestionen acerca de la posibilidad de trabajar para dicha organizaci\u00f3n. Es por ello que un beneficio del contenido que generen tus empleados, puede verse reflejado en reclutamientos m\u00e1s efectivos con candidatos proactivos que se encuentren realmente interesados en participar.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>No olvides que para maximizar el aprovechamiento del contenido generado por los colaboradores puedes:<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:list --><\/p>\n<ul>\n<li><strong>Organizar actividades y din\u00e1micas:<\/strong>\u00a0Puedes sugerir concursos o colaboraciones que motiven a tus colaboradores a participar y compartir sus experiencias, creatividad y conocimientos sobre tu marca, con los dem\u00e1s; as\u00ed ellos podr\u00e1n obtener recompensas y visibilidad laboral.\u00a0<br \/><br \/><\/li>\n<li><strong>Crear lineamientos creativos:<\/strong>\u00a0Puedes brindarles lineamientos de c\u00f3mo realizar el contenido. Para ello, debes redactar un documento interno que contenga indicaciones, as\u00ed ellos sabr\u00e1n si utilizar\u00e1n alg\u00fan\u00a0<em>hashtag<\/em>, se identificar\u00e1n de alguna manera como parte de la empresa, deber\u00e1n informarse sobre los temas autorizados o si pueden compartir fotos de las instalaciones sin impedimentos legales.<br \/><br \/><\/li>\n<li><strong>Acepta el liderazgo:<\/strong>\u00a0Mostrar compromiso y transparencia con el contenido generado, da la oportunidad de ver reflejado en \u00e9l, el liderazgo de tu equipo.<\/li>\n<\/ul>\n<p><!-- \/wp:list --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Las\u00a0<strong><a href=\"https:\/\/www.marketinginsiderreview.com\/que-son-relaciones-publicas\/\" target=\"_blank\" rel=\"noreferrer noopener\">relaciones p\u00fablicas<\/a>\u00a0<\/strong>y sus tendencias cambian seg\u00fan los momentos en los que la sociedad se encuentre, es por ello que insertar la tendencia del contenido generado por empleados, te ayudar\u00e1 a impulsar tu estrategia de RP y marketing de contenidos de forma org\u00e1nica; adem\u00e1s, fortalecer\u00e1s tu comunicaci\u00f3n organizacional.\u00a0<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Este contenido apareci\u00f3 por primera vez en <strong><a href=\"https:\/\/www.marketinginsiderreview.com\/razones-aprovechar-contenido-empleados-estrategia-rrpp\/\" target=\"_blank\" rel=\"noreferrer noopener\">Marketing Insider Review<\/a><\/strong>.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<p><!-- wp:paragraph --><\/p>\n<p>Conoce m\u00e1s contenido del autor en <a href=\"https:\/\/www.marketinginsiderreview.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Marketing Insider Review<\/strong><\/a>.<\/p>\n<p><!-- \/wp:paragraph --><\/p>","protected":false},"excerpt":{"rendered":"<p>Estrategias de marketing y relaciones p\u00fablicas para humanizar y posicionar la marca mediante EGC contenido generado por empleados.<\/p>\n","protected":false},"author":2,"featured_media":18169,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","_ayudawp_aiss_exclude":false,"_joinchat":[],"footnotes":""},"categories":[491],"tags":[1291,1307,1314,2010,2905],"class_list":["post-7307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mangement","tag-estrategias-de-marketing","tag-estrategias-de-posicionamiento-de-marca","tag-estrategias-de-relaciones-publicas","tag-humanizacion-de-marca","tag-articulos"],"a3_pvc":{"activated":false,"total_views":34,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones<\/title>\n<meta name=\"description\" content=\"Estrategias de marketing y relaciones p\u00fablicas para humanizar y posicionar la marca mediante EGC contenido generado por empleados.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP\" \/>\n<meta property=\"og:description\" content=\"Estrategias de marketing y relaciones p\u00fablicas para humanizar y posicionar la marca mediante EGC contenido generado por empleados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/\" \/>\n<meta property=\"og:site_name\" content=\"Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/infosol\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/HectorM.MezaC?ref=br_rs_WyJrZXl3b3Jkc191c2VycyJd\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-21T14:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T20:49:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"H\u00e9ctor M. Meza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP\" \/>\n<meta name=\"twitter:description\" content=\"Estrategias de marketing y relaciones p\u00fablicas para humanizar y posicionar la marca mediante EGC contenido generado por empleados.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp-2.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/HectorMezaC\" \/>\n<meta name=\"twitter:site\" content=\"@EspacioInfoSol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"H\u00e9ctor M. Meza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/\"},\"author\":{\"name\":\"H\u00e9ctor M. Meza\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#\\\/schema\\\/person\\\/bb70f136abbd7e36b1f997a14c53ac3a\"},\"headline\":\"3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP\",\"datePublished\":\"2022-07-21T14:02:00+00:00\",\"dateModified\":\"2025-07-07T20:49:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/\"},\"wordCount\":897,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/estrategias-de-posicionamiento-de-marca.webp\",\"keywords\":[\"Estrategias de marketing\",\"Estrategias de posicionamiento de marca\",\"Estrategias de relaciones p\u00fablicas\",\"Humanizaci\u00f3n de marca\",\"Art\u00edculos\"],\"articleSection\":[\"Management\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/\",\"name\":\"3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/estrategias-de-posicionamiento-de-marca.webp\",\"datePublished\":\"2022-07-21T14:02:00+00:00\",\"dateModified\":\"2025-07-07T20:49:20+00:00\",\"description\":\"Estrategias de marketing y relaciones p\u00fablicas para humanizar y posicionar la marca mediante EGC contenido generado por empleados.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/estrategias-de-posicionamiento-de-marca.webp\",\"contentUrl\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/estrategias-de-posicionamiento-de-marca.webp\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Management\",\"item\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/category\\\/mangement\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/\",\"name\":\"Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones\",\"description\":\"Comunicaci\u00f3n, Relaciones P\u00fablicas, Redes Sociales y algo m\u00e1s...\",\"publisher\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#organization\",\"name\":\"InfoSol\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/InfoSol-6.0-160x46-1.webp\",\"contentUrl\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/InfoSol-6.0-160x46-1.webp\",\"width\":160,\"height\":46,\"caption\":\"InfoSol\"},\"image\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infosol\\\/\",\"https:\\\/\\\/x.com\\\/EspacioInfoSol\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/grupoinfosol\\\/\",\"https:\\\/\\\/www.pinterest.com.mx\\\/GrupoInfoSol\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/InfoSolMiEspacio\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#\\\/schema\\\/person\\\/bb70f136abbd7e36b1f997a14c53ac3a\",\"name\":\"H\u00e9ctor M. Meza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/cropped-h-meza-96x96.png\",\"url\":\"http:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/cropped-h-meza-96x96.png\",\"contentUrl\":\"http:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/cropped-h-meza-96x96.png\",\"caption\":\"H\u00e9ctor M. Meza\"},\"description\":\"Director General de InfoSol. MBA, Consultor y Catedr\u00e1tico en Estrategias de Comunicaci\u00f3n Integradas a la Mercadotecnia. Fue Vicepresidente en IBM de M\u00e9xico y Presidente de Motorola para M\u00e9xico, Centroam\u00e9rica y el Caribe y VP de la Corporaci\u00f3n.\",\"sameAs\":[\"http:\\\/\\\/www.infosol.com.mx\",\"https:\\\/\\\/www.facebook.com\\\/HectorM.MezaC?ref=br_rs_WyJrZXl3b3Jkc191c2VycyJd\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/h\u00e9ctor-meza-curiel\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/HectorMezaC\"],\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/author\\\/h-meza\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","description":"Estrategias de marketing y relaciones p\u00fablicas para humanizar y posicionar la marca mediante EGC contenido generado por empleados.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/","og_locale":"es_ES","og_type":"article","og_title":"3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP","og_description":"Estrategias de marketing y relaciones p\u00fablicas para humanizar y posicionar la marca mediante EGC contenido generado por empleados.","og_url":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/","og_site_name":"Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","article_publisher":"https:\/\/www.facebook.com\/infosol\/","article_author":"https:\/\/www.facebook.com\/HectorM.MezaC?ref=br_rs_WyJrZXl3b3Jkc191c2VycyJd","article_published_time":"2022-07-21T14:02:00+00:00","article_modified_time":"2025-07-07T20:49:20+00:00","og_image":[{"width":1400,"height":600,"url":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp-2.jpg","type":"image\/jpeg"}],"author":"H\u00e9ctor M. Meza","twitter_card":"summary_large_image","twitter_title":"3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP","twitter_description":"Estrategias de marketing y relaciones p\u00fablicas para humanizar y posicionar la marca mediante EGC contenido generado por empleados.","twitter_image":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp-2.jpg","twitter_creator":"@https:\/\/twitter.com\/HectorMezaC","twitter_site":"@EspacioInfoSol","twitter_misc":{"Escrito por":"H\u00e9ctor M. Meza","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/#article","isPartOf":{"@id":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/"},"author":{"name":"H\u00e9ctor M. Meza","@id":"https:\/\/infosol.com.mx\/wordpress\/#\/schema\/person\/bb70f136abbd7e36b1f997a14c53ac3a"},"headline":"3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP","datePublished":"2022-07-21T14:02:00+00:00","dateModified":"2025-07-07T20:49:20+00:00","mainEntityOfPage":{"@id":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/"},"wordCount":897,"commentCount":0,"publisher":{"@id":"https:\/\/infosol.com.mx\/wordpress\/#organization"},"image":{"@id":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/#primaryimage"},"thumbnailUrl":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/estrategias-de-posicionamiento-de-marca.webp","keywords":["Estrategias de marketing","Estrategias de posicionamiento de marca","Estrategias de relaciones p\u00fablicas","Humanizaci\u00f3n de marca","Art\u00edculos"],"articleSection":["Management"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/","url":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/","name":"3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","isPartOf":{"@id":"https:\/\/infosol.com.mx\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/#primaryimage"},"image":{"@id":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/#primaryimage"},"thumbnailUrl":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/estrategias-de-posicionamiento-de-marca.webp","datePublished":"2022-07-21T14:02:00+00:00","dateModified":"2025-07-07T20:49:20+00:00","description":"Estrategias de marketing y relaciones p\u00fablicas para humanizar y posicionar la marca mediante EGC contenido generado por empleados.","breadcrumb":{"@id":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/#primaryimage","url":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/estrategias-de-posicionamiento-de-marca.webp","contentUrl":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/estrategias-de-posicionamiento-de-marca.webp","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/infosol.com.mx\/wordpress\/3-importantes-razones-para-aprovechar-el-contenido-generado-por-empleados-en-tu-estrategia-de-rrpp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/infosol.com.mx\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Management","item":"https:\/\/infosol.com.mx\/wordpress\/category\/mangement\/"},{"@type":"ListItem","position":3,"name":"3 importantes razones para aprovechar el contenido generado por empleados en tu estrategia de RRPP"}]},{"@type":"WebSite","@id":"https:\/\/infosol.com.mx\/wordpress\/#website","url":"https:\/\/infosol.com.mx\/wordpress\/","name":"Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","description":"Comunicaci\u00f3n, Relaciones P\u00fablicas, Redes Sociales y algo m\u00e1s...","publisher":{"@id":"https:\/\/infosol.com.mx\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infosol.com.mx\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infosol.com.mx\/wordpress\/#organization","name":"InfoSol","url":"https:\/\/infosol.com.mx\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infosol.com.mx\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/InfoSol-6.0-160x46-1.webp","contentUrl":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/InfoSol-6.0-160x46-1.webp","width":160,"height":46,"caption":"InfoSol"},"image":{"@id":"https:\/\/infosol.com.mx\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infosol\/","https:\/\/x.com\/EspacioInfoSol","https:\/\/www.linkedin.com\/company\/grupoinfosol\/","https:\/\/www.pinterest.com.mx\/GrupoInfoSol\/","https:\/\/www.youtube.com\/user\/InfoSolMiEspacio"]},{"@type":"Person","@id":"https:\/\/infosol.com.mx\/wordpress\/#\/schema\/person\/bb70f136abbd7e36b1f997a14c53ac3a","name":"H\u00e9ctor M. Meza","image":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/cropped-h-meza-96x96.png","url":"http:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/cropped-h-meza-96x96.png","contentUrl":"http:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/cropped-h-meza-96x96.png","caption":"H\u00e9ctor M. Meza"},"description":"Director General de InfoSol. MBA, Consultor y Catedr\u00e1tico en Estrategias de Comunicaci\u00f3n Integradas a la Mercadotecnia. Fue Vicepresidente en IBM de M\u00e9xico y Presidente de Motorola para M\u00e9xico, Centroam\u00e9rica y el Caribe y VP de la Corporaci\u00f3n.","sameAs":["http:\/\/www.infosol.com.mx","https:\/\/www.facebook.com\/HectorM.MezaC?ref=br_rs_WyJrZXl3b3Jkc191c2VycyJd","https:\/\/www.linkedin.com\/in\/h\u00e9ctor-meza-curiel\/","https:\/\/x.com\/https:\/\/twitter.com\/HectorMezaC"],"url":"https:\/\/infosol.com.mx\/wordpress\/author\/h-meza\/"}]}},"_links":{"self":[{"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/posts\/7307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/comments?post=7307"}],"version-history":[{"count":21,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/posts\/7307\/revisions"}],"predecessor-version":[{"id":18172,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/posts\/7307\/revisions\/18172"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/media\/18169"}],"wp:attachment":[{"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/media?parent=7307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/categories?post=7307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/tags?post=7307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}