{"id":2897,"date":"2016-06-16T16:16:34","date_gmt":"2016-06-16T21:16:34","guid":{"rendered":"http:\/\/infosol.com.mx\/wordpress\/?p=2897"},"modified":"2026-07-16T11:39:53","modified_gmt":"2026-07-16T17:39:53","slug":"agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas","status":"publish","type":"post","link":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/","title":{"rendered":"Agencias de Contenidos Impulsados por Datos \u00bfPor qu\u00e9 acudir a ellas?"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.7&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb custom_padding=\u00bb||0px||false|false\u00bb sticky_enabled=\u00bb0&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.7&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>A lo largo de mi caminar como consultor en Relaciones P\u00fablicas, me ha tocado ver el d\u00eda a d\u00eda de mis contactos de Marketing y Comunicaci\u00f3n (MARCOM), los cuales adem\u00e1s de coordinar las actividades de RP; tienen que realizar investigaciones de mercado, eventos, coordinar a las agencias de Publicidad, Dise\u00f1o y Redes Sociales, as\u00ed como manejar presupuestos con la consigna de hacer magia, m\u00e1s con menos.<\/p>\n<p>Adem\u00e1s de que, otra de sus funciones es alimentar y enriquecer sus Medios Propios (blogs, p\u00e1gina web, revistas internas, <em>whitepapers<\/em>, entre otros) con contenidos que agreguen valor a sus clientes actuales y potenciales, adem\u00e1s de capitalizarlos en su Relaci\u00f3n con Medios e Influenciadores Digitales y, la pregunta que surge es: \u00bfen qu\u00e9 momento me pongo a redactar los contenidos?<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; disabled_on=\u00bboff|off|off\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(168,30,100,0.31)\u00bb background_enable_image=\u00bboff\u00bb background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_horizontal_offset=\u00bb0%\u00bb custom_margin=\u00bb25px||50px||false|false\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb border_width_all=\u00bb2px\u00bb border_color_all=\u00bb#0595a8&#8243; box_shadow_style=\u00bbpreset4&#8243; box_shadow_horizontal=\u00bb0px\u00bb box_shadow_color=\u00bb#081116&#8243; locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_enable_color=\u00bboff\u00bb custom_margin=\u00bb0px||0px||true|false\u00bb custom_padding=\u00bb5px||5px||true|false\u00bb border_radii=\u00bbon|25px|25px|25px|25px\u00bb border_style_all=\u00bbnone\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text content_tablet=\u00bb<\/p>\n<h5><strong>Recuerda: RP NO es lo mismo que publicidad ni marketing<\/strong><\/h5>\n<h6>Ten en cuenta que <strong>las relaciones p\u00fablicas no buscan vender directamente<\/strong>, sino <strong>influir en la percepci\u00f3n<\/strong>, construir reputaci\u00f3n, generar conversaci\u00f3n org\u00e1nica y conectar a la marca con sus audiencias mediante terceros: medios, l\u00edderes de opini\u00f3n, comunidades o alianzas estrat\u00e9gicas. Esa es la diferencia clave que ver\u00e1s reflejada en cada caso a continuaci\u00f3n.<\/h6>\n<p>\u00bb content_phone=\u00bb<\/p>\n<h5><strong>\u00bfSab\u00edas que\u2026?<\/strong><\/h5>\n<h6>El 78% de las empresas que miden KPIs en RP logran optimizar sus campa\u00f1as y mejorar su reputaci\u00f3n online en menos de un a\u00f1o, apoy\u00e1ndose en datos confiables y su an\u00e1lisis, de acuerdo con un reporte global de Cision y PRWeek.<\/h6>\n<p>\u00bb content_last_edited=\u00bbon|desktop\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bbOswald|700|||||||\u00bb text_text_color=\u00bb#3c4046&#8243; text_font_size=\u00bb25px\u00bb ul_font=\u00bbEditorialNew-Light|300|||||||\u00bb ul_text_color=\u00bb#000000&#8243; ul_font_size=\u00bb1.25rem\u00bb ul_line_height=\u00bb1.6em\u00bb header_5_font=\u00bb|||on|||||\u00bb header_5_text_color=\u00bb#081116&#8243; header_5_font_size=\u00bb1.4rem\u00bb header_6_font=\u00bbEditorialNew-Light||||||||\u00bb header_6_text_color=\u00bb#081116&#8243; header_6_font_size=\u00bb1.3rem\u00bb header_6_line_height=\u00bb1.3em\u00bb background_enable_color=\u00bboff\u00bb background_image=\u00bbhttps:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/sabias-que_.webp\u00bb background_size=\u00bbcustom\u00bb background_image_width=\u00bb12%\u00bb background_position=\u00bbtop_right\u00bb background_horizontal_offset=\u00bb4%\u00bb background_vertical_offset=\u00bb40%\u00bb custom_padding=\u00bb25px|200px|20px|50px|false|false\u00bb custom_padding_tablet=\u00bb25px|200px|20px|50px|false|false\u00bb custom_padding_phone=\u00bb60px|25px|10px|25px|false|true\u00bb custom_padding_last_edited=\u00bbon|phone\u00bb hover_enabled=\u00bb0&#8243; background_last_edited=\u00bbon|phone\u00bb background_image_width_phone=\u00bb27%\u00bb background_horizontal_offset_phone=\u00bb5%\u00bb background_vertical_offset_phone=\u00bb1%\u00bb custom_css_main_element=\u00bbul {margin-top:25px;}\u00bb border_radii=\u00bbon|20px|20px|20px|20px\u00bb box_shadow_style=\u00bbpreset3&#8243; box_shadow_color=\u00bbrgba(0,0,0,0.15)\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb custom_css_main_element_last_edited=\u00bbon|phone\u00bb custom_css_main_element_phone=\u00bbbackground-position: right 4% top 0% !important;\u00bb custom_css_main_element_tablet=\u00bbul {margin-top:25px;}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<h6>60% de los CMOs (Gerentes de Marketing) prev\u00e9n un incremento en los presupuestos en Marketing de Contenidos como resultado de un positivo ROI.<\/h6>\n<p><span style=\"text-align: right;\">Fortune<\/span>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.7&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb sticky_enabled=\u00bb0&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.7&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p><!-- \/divi:heading --><\/p>\n<p><span>Actualmente, los MARCOM tienen la posibilidad de delegar esa tarea tan importante a los expertos en la creaci\u00f3n de Contenidos Impulsados por Datos (<\/span><em style=\"font-size: 20px; font-variant-ligatures: inherit; font-variant-caps: inherit;\">Data Driven Content Marketing<\/em><span style=\"font-size: 20px; font-style: inherit; font-variant-ligatures: inherit; font-variant-caps: inherit;\">), la cual combina experiencia y talento para redactar contenidos en diversos formatos multimedia y de acuerdo al momento en el Ciclo de Compra -Posicionamiento, Consideraci\u00f3n y Acci\u00f3n- en el que se encuentren las audiencias, as\u00ed como combinar el atractivo indiscutible que tienen los n\u00fameros ya sean de encuestas, indicadores econ\u00f3micos, tendencias, estimaciones, investigaciones, etc\u00e9tera, para dar credibilidad, contexto y valor a los contenidos.<\/span><\/p>\n<p>De acuerdo con Fortune, las compa\u00f1\u00edas pertenecientes a la lista Fortune 500, gastan en promedio, entre 26% y 50% de sus presupuestos en Marketing de Contenidos y es que una estrategia de Periodismo de Marca (<em>Brand Journalism<\/em>) consiste precisamente en contar la historia de la marca y crear una conexi\u00f3n emocional con sus audiencias es por eso que una buena idea es dejar a los expertos que cuenten y reporten la historia de su compa\u00f1\u00eda alrededor de los datos, pues como dijo la Madre Teresa de Calcuta: \u00ab<em>Yo hago lo que usted no puede y usted hace lo que yo no puedo. Juntos podemos hacer grandes cosas\u00bb<\/em>.<\/p>\n<p><strong>Tambi\u00e9n te puede interesar:<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb background_enable_color=\u00bboff\u00bb custom_margin=\u00bb0px||25px||false|false\u00bb custom_padding=\u00bb25px||0px||false|false\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row use_custom_gutter=\u00bbon\u00bb gutter_width=\u00bb1&#8243; make_equal=\u00bbon\u00bb _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(5,149,168,0.73)\u00bb custom_margin=\u00bb0px||0px||false|false\u00bb custom_padding=\u00bb16px|25px|1px|25px|false|true\u00bb border_width_top=\u00bb1px\u00bb border_width_bottom=\u00bb1px\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb0px||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][dpdfg_filtergrid custom_query=\u00bbposts_ids\u00bb posts_ids=\u00bb409&#8243; post_number=\u00bb1&#8243; thumbnail_size=\u00bb510&#215;382&#8243; use_overlay=\u00bboff\u00bb title_link=\u00bbon\u00bb show_post_meta=\u00bboff\u00bb read_more_window=\u00bbon\u00bb custom_content_container=\u00bboff\u00bb show_filters=\u00bboff\u00bb show_pagination=\u00bboff\u00bb items_layout=\u00bbdp-dfg-layout-list\u00bb thumb_min_width=\u00bb36%\u00bb thumb_width=\u00bb36%\u00bb column_gutter=\u00bb0em\u00bb row_gutter=\u00bb0em\u00bb items_skin=\u00bbdp-dfg-skin-none\u00bb primary_view=\u00bb%91{%22name%22:%22thumbnail%22,%22show%22:%22on%22},{%22name%22:%22overlay%22,%22show%22:%22on%22},{%22name%22:%22title%22,%22show%22:%22off%22},{%22name%22:%22meta%22,%22show%22:%22off%22},{%22name%22:%22ext%22,%22show%22:%22off%22},{%22name%22:%22content%22,%22show%22:%22off%22},{%22name%22:%22read_more_button%22,%22show%22:%22off%22},{%22name%22:%22action_button%22,%22show%22:%22off%22},{%22name%22:%22custom_content%22,%22show%22:%22off%22}%93&#8243; secondary_view=\u00bb%91{%22name%22:%22thumbnail%22,%22show%22:%22off%22},{%22name%22:%22meta%22,%22show%22:%22on%22},{%22name%22:%22title%22,%22show%22:%22on%22},{%22name%22:%22ext%22,%22show%22:%22on%22},{%22name%22:%22content%22,%22show%22:%22on%22},{%22name%22:%22action_button%22,%22show%22:%22on%22},{%22name%22:%22read_more_button%22,%22show%22:%22on%22},{%22name%22:%22custom_content%22,%22show%22:%22on%22}%93&#8243; bg_items=\u00bbRGBA(255,255,255,0)\u00bb _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb dpdfg_entry_title_level=\u00bbh6&#8243; dpdfg_entry_title_font=\u00bbOswald|||on|||||\u00bb dpdfg_entry_title_text_color=\u00bb#506ebb\u00bb dpdfg_entry_title_font_size=\u00bb1.2rem\u00bb dpdfg_entry_title_line_height=\u00bb1.1em\u00bb dpdfg_entry_summary_font=\u00bbEditorialNew-Light||||||||\u00bb dpdfg_entry_summary_text_color=\u00bb#FFFFFF\u00bb dpdfg_entry_summary_font_size=\u00bb1.5rem\u00bb dpdfg_entry_summary_line_height=\u00bb1.2em\u00bb background_enable_color=\u00bboff\u00bb custom_read_more_button=\u00bbon\u00bb read_more_button_text_color=\u00bb#FFFFFF\u00bb read_more_button_font=\u00bbOswald|||on|||||\u00bb read_more_button_icon=\u00bb&#x24;||divi||400&#8243; read_more_button_on_hover=\u00bboff\u00bb read_more_button_alignment=\u00bbcenter\u00bb read_more_button_custom_margin=\u00bb||0px||false|false\u00bb read_more_button_custom_padding=\u00bb||||false|false\u00bb height=\u00bb80px\u00bb height_tablet=\u00bb85px\u00bb height_phone=\u00bb125px\u00bb height_last_edited=\u00bbon|tablet\u00bb custom_margin=\u00bb0px|0px|0px|0px|false|false\u00bb custom_padding=\u00bb0px|0px|0px|0px|false|false\u00bb hover_enabled=\u00bb0&#8243; dpdfg_entry_title_line_height_tablet=\u00bb1.4em\u00bb dpdfg_entry_title_line_height_phone=\u00bb1.4em\u00bb dpdfg_entry_title_line_height_last_edited=\u00bbon|phone\u00bb custom_css_entry-thumb=\u00bbwidth: 120px;||height: auto;\u00bb custom_css_entry-header=\u00bbmargin-left: -210px;||padding-top: 12px;\u00bb border_radii=\u00bboff||||\u00bb border_color_all=\u00bb#000000&#8243; border_width_top=\u00bb2px\u00bb border_width_bottom=\u00bb2px\u00bb global_colors_info=\u00bb{}\u00bb custom_css_entry-header_last_edited=\u00bbon|tablet\u00bb custom_css_entry-header_phone=\u00bbmargin-left: 130px;||padding-top: 0px;||margin-top: -80px;||width:63%;\u00bb custom_css_entry-header_tablet=\u00bbmargin-left: -170px;||padding-top: 0px;\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;][\/dpdfg_filtergrid][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.27.7&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb custom_padding=\u00bb0px||0px||true|false\u00bb sticky_enabled=\u00bb0&#8243;][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<\/p>\n<p>Y es por eso por lo que contar con un aliado en la generaci\u00f3n de contenidos que atraigan y generen un mayor compromiso de las audiencias con las marcas, puede ser lo que necesita tu negocio y precisamente quiero compartirte cinco puntos que debes de considerar para esta labor:<\/p>\n<ol class=\"wp-block-list\">\n<li><strong>Utiliza datos como la base del contenido:<\/strong> Todo comienza con el uso de los datos para dar forma al contenido seg\u00fan las necesidades de la audiencia de forma personalizada y relevante. \u00bfC\u00f3mo es su consumo de informaci\u00f3n? \u00bfQu\u00e9 les gusta leer? \u00bfA qu\u00e9 fase del ciclo de compra se dirigir\u00e1 la historia? \u00bfConcientizaci\u00f3n? \u00bfConsideraci\u00f3n? \u00bfAcci\u00f3n? Ahora s\u00ed, a generar una buena historia que, por supuesto, utilice datos como narrativa central, ya sean de tendencias, ranqueos o tablas de clasificaci\u00f3n, comparaciones, datos sorprendentes o contrarios a la intuici\u00f3n y relaciones.<\/li>\n<li><strong>Soluci\u00f3n de Marketing flexible y a la medida de las compa\u00f1\u00edas:<\/strong> El CMO tiene m\u00faltiples tareas muy importantes. Una Agencia de Contenidos Impulsados por Datos le ayudar\u00e1 a contar con una soluci\u00f3n de contenido alineada a la Estrategia de Medios Ganados que apoya la consecuci\u00f3n de los objetivos de Comunicaci\u00f3n y la difusi\u00f3n propuesta de valor de la marca con contenido valioso, \u00fatil, fresco y relevante para generar mayor inter\u00e9s de las audiencias hacia la marca y que \u00e9sta se convierta en la marca de elecci\u00f3n.<\/li>\n<li><strong>Crea el contenido en conjunto con la marca:<\/strong> Esto incluye el trabajo con diferentes expertos para crear art\u00edculos que humanicen y reflejen claramente la visi\u00f3n de la marca ya sea para Redes Sociales, Historias de \u00c9xito entre un sinf\u00edn de formatos que el <em>Content Marketing<\/em><\/li>\n<li><strong>Expertos en <em>Storytelling<\/em>, redacci\u00f3n y generaci\u00f3n de noticias:<\/strong> Contar con una Agencia especializada en Contenidos permite contar con experiencia y talento period\u00edstico en diferentes industrias y temas para contar historias y reportar hechos noticiosos de una manera atractiva, conectando emocionalmente con tus audiencias.<\/li>\n<li><strong>Constructores de la reputaci\u00f3n corporativa: <\/strong>A trav\u00e9s de la generaci\u00f3n constante de contenidos que integran los mensajes clave, opiniones y visi\u00f3n de negocio de la empresa, pero sobre todo que brinda informaci\u00f3n de utilidad a las audiencias y de c\u00f3mo facilitarle el d\u00eda a d\u00eda a trav\u00e9s de las soluciones o servicios que provee la marca, se construye una imagen positiva ya que se fortalece la percepci\u00f3n como fuente confiable de la industria y referente de su sector.<\/li>\n<\/ol>\n<p><em>\u00abEl nuevo rol de la agencia consiste en crear contenido de tal valor que el consumidor no querr\u00e1 vivir sin \u00e9l\u00bb,<\/em> as\u00ed lo coment\u00f3 Jeff Hicks, CEO de Crispin, Porter y Bogusky y es que Contar con una Agencia de Contenidos Impulsados por Datos proporciona una perspectiva valiosa al no est\u00e1n limitados por la din\u00e1mica de tu organizaci\u00f3n o pol\u00edticas internas, y pueden abordar tus retos de contenido con una visi\u00f3n objetiva, y al estar en alerta constante de\u00a0 oportunidades, que tal vez no se encuentren en tu radar, pueden apalancarse de diversas tendencias de comunicaci\u00f3n como Newsjacking y\u00a0 Eventos de Temporada.<\/p>\n<p>Cabe destacar que la producci\u00f3n de contenidos es s\u00f3lo una peque\u00f1a parte de todo el tesoro que el <strong>Marketing de Contenidos<\/strong> ofrece, sin embargo cada vez m\u00e1s son las compa\u00f1\u00edas que palpan el valor de crear y compartir contenidos de valor alrededor de los datos, con el fin de iniciar la conversaci\u00f3n con sus audiencias, provocando su viralidad y complementando la historia de la compa\u00f1\u00eda con sus experiencias.<\/p>\n<p><strong>**Colaboraci\u00f3n basada en el art\u00edculo Data Driven Content: Ideas that Work in Content Marketing de Richard Braxter.<\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A lo largo de mi caminar como consultor en Relaciones P\u00fablicas, me ha tocado ver el d\u00eda a d\u00eda de mis contactos de Marketing y Comunicaci\u00f3n (MARCOM), los cuales adem\u00e1s de coordinar las actividades de RP; tienen que realizar investigaciones de mercado, eventos, coordinar a las agencias de Publicidad, Dise\u00f1o y Redes Sociales, as\u00ed como [&hellip;]<\/p>\n","protected":false},"author":21,"featured_media":18234,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:paragraph -->\n<p>A lo largo de mi caminar como consultor en Relaciones P\u00fablicas, me ha tocado ver el d\u00eda a d\u00eda de mis contactos de Marketing y Comunicaci\u00f3n (MARCOM), los cuales adem\u00e1s de coordinar las actividades de RP; tienen que realizar investigaciones de mercado, eventos, coordinar a las agencias de Publicidad, Dise\u00f1o y Redes Sociales, as\u00ed como manejar presupuestos con la consigna de hacer magia, m\u00e1s con menos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Adem\u00e1s de que, otra de sus funciones es alimentar y enriquecer sus Medios Propios (blogs, p\u00e1gina web, revistas internas, <em>whitepapers<\/em>, entre otros) con contenidos que agreguen valor a sus clientes actuales y potenciales, adem\u00e1s de capitalizarlos en su Relaci\u00f3n con Medios e Influenciadores Digitales y, la pregunta que surge es: \u00bfen qu\u00e9 momento me pongo a redactar los contenidos?<em> <\/em><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:quote -->\n<blockquote class=\"wp-block-quote\"><!-- wp:paragraph -->\n<p>60% de los CMOs (Gerentes de Marketing) prev\u00e9n un incremento en los presupuestos en Marketing de Contenidos como resultado de un positivo ROI.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:heading {\"level\":3} -->\n<h3 class=\"wp-block-heading\">Fortune<\/h3>\n<!-- \/wp:heading --><\/blockquote>\n<!-- \/wp:quote -->\n\n<!-- wp:paragraph -->\n<p>Actualmente, los MARCOM tienen la posibilidad de delegar esa tarea tan importante a los expertos en la creaci\u00f3n de Contenidos Impulsados por Datos (<em>Data Driven Content Marketing<\/em>), la cual combina experiencia y talento para redactar contenidos en diversos formatos multimedia y de acuerdo al momento en el Ciclo de Compra -Posicionamiento, Consideraci\u00f3n y Acci\u00f3n- en el que se encuentren las audiencias, as\u00ed como combinar el atractivo indiscutible que tienen los n\u00fameros ya sean de encuestas, indicadores econ\u00f3micos, tendencias, estimaciones, investigaciones, etc\u00e9tera, para dar credibilidad, contexto y valor a los contenidos.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>De acuerdo con Fortune, las compa\u00f1\u00edas pertenecientes a la lista Fortune 500, gastan en promedio, entre 26% y 50% de sus presupuestos en Marketing de Contenidos y es que una estrategia de Periodismo de Marca (<em>Brand Journalism<\/em>) consiste precisamente en contar la historia de la marca y crear una conexi\u00f3n emocional con sus audiencias es por eso que una buena idea es dejar a los expertos que cuenten y reporten la historia de su compa\u00f1\u00eda alrededor de los datos, pues como dijo la Madre Teresa de Calcuta: \"<em>Yo hago lo que usted no puede y usted hace lo que yo no puedo. Juntos podemos hacer grandes cosas\"<\/em>.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong>Tambi\u00e9n te puede interesar:<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:html -->\n<article id=\"post-409\">\n<figure><figure><img src=\"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/cropped-que-es-el-periodismo-de-marca-700x450.jpg\" alt=\"\" width=\"700\" height=\"450\"><\/figure><\/figure>\n<header>Tags\n<ul>\n<li><a href=\"https:\/\/infosol.com.mx\/wordpress\/category\/marketing-de-contenido\/\" rel=\"category\">Marketing de Contenidos<\/a><\/li>\n<\/ul>\n<h2><a href=\"https:\/\/infosol.com.mx\/wordpress\/8-maneras-de-crear-periodismo-de-refrigerador\/\">\u00bfQu\u00e9 es el periodismo de marca?<\/a><\/h2>\n<\/header>\n<p>Seguramente has escuchado o le\u00eddo sobre este concepto. Si quieres saber c\u00f3mo aplicarlo, aqu\u00ed te compartimos 4 consejos b\u00e1sicos.<\/p>\n<\/article>\n<!-- \/wp:html -->\n\n<!-- wp:paragraph -->\n<p>&nbsp;<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Y es por eso por lo que contar con un aliado en la generaci\u00f3n de contenidos que atraigan y generen un mayor compromiso de las audiencias con las marcas, puede ser lo que necesita tu negocio y precisamente quiero compartirte cinco puntos que debes de considerar para esta labor:\u00a0<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list {\"ordered\":true} -->\n<ol class=\"wp-block-list\"><!-- wp:list-item -->\n<li><strong>Utiliza datos como la base del contenido:<\/strong> Todo comienza con el uso de los datos para dar forma al contenido seg\u00fan las necesidades de la audiencia de forma personalizada y relevante. \u00bfC\u00f3mo es su consumo de informaci\u00f3n? \u00bfQu\u00e9 les gusta leer? \u00bfA qu\u00e9 fase del ciclo de compra se dirigir\u00e1 la historia? \u00bfConcientizaci\u00f3n? \u00bfConsideraci\u00f3n? \u00bfAcci\u00f3n? Ahora s\u00ed, a generar una buena historia que, por supuesto, utilice datos como narrativa central, ya sean de tendencias, ranqueos o tablas de clasificaci\u00f3n, comparaciones, datos sorprendentes o contrarios a la intuici\u00f3n y relaciones.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Soluci\u00f3n de Marketing flexible y a la medida de las compa\u00f1\u00edas:<\/strong> El CMO tiene m\u00faltiples tareas muy importantes. Una Agencia de Contenidos Impulsados por Datos le ayudar\u00e1 a contar con una soluci\u00f3n de contenido alineada a la Estrategia de Medios Ganados que apoya la consecuci\u00f3n de los objetivos de Comunicaci\u00f3n y la difusi\u00f3n propuesta de valor de la marca con contenido valioso, \u00fatil, fresco y relevante para generar mayor inter\u00e9s de las audiencias hacia la marca y que \u00e9sta se convierta en la marca de elecci\u00f3n.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Crea el contenido en conjunto con la marca:<\/strong> Esto incluye el trabajo con diferentes expertos para crear art\u00edculos que humanicen y reflejen claramente la visi\u00f3n de la marca ya sea para Redes Sociales, Historias de \u00c9xito entre un sinf\u00edn de formatos que el <em>Content Marketing<\/em><\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Expertos en <em>Storytelling<\/em>, redacci\u00f3n y generaci\u00f3n de noticias:<\/strong> Contar con una Agencia especializada en Contenidos permite contar con experiencia y talento period\u00edstico en diferentes industrias y temas para contar historias y reportar hechos noticiosos de una manera atractiva, conectando emocionalmente con tus audiencias.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li><strong>Constructores de la reputaci\u00f3n corporativa: <\/strong>A trav\u00e9s de la generaci\u00f3n constante de contenidos que integran los mensajes clave, opiniones y visi\u00f3n de negocio de la empresa, pero sobre todo que brinda informaci\u00f3n de utilidad a las audiencias y de c\u00f3mo facilitarle el d\u00eda a d\u00eda a trav\u00e9s de las soluciones o servicios que provee la marca, se construye una imagen positiva ya que se fortalece la percepci\u00f3n como fuente confiable de la industria y referente de su sector.<\/li>\n<!-- \/wp:list-item --><\/ol>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>\u00a0<em>\"El nuevo rol de la agencia consiste en crear contenido de tal valor que el consumidor no querr\u00e1 vivir sin \u00e9l\",<\/em> as\u00ed lo coment\u00f3 Jeff Hicks, CEO de Crispin, Porter y Bogusky y es que Contar con una Agencia de Contenidos Impulsados por Datos proporciona una perspectiva valiosa al no est\u00e1n limitados por la din\u00e1mica de tu organizaci\u00f3n o pol\u00edticas internas, y pueden abordar tus retos de contenido con una visi\u00f3n objetiva, y al estar en alerta constante de\u00a0 oportunidades, que tal vez no se encuentren en tu radar, pueden apalancarse de diversas tendencias de comunicaci\u00f3n como Newsjacking y\u00a0 Eventos de Temporada.\u00a0<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Cabe destacar que la producci\u00f3n de contenidos es s\u00f3lo una peque\u00f1a parte de todo el tesoro que el <strong>Marketing de Contenidos<\/strong> ofrece, sin embargo cada vez m\u00e1s son las compa\u00f1\u00edas que palpan el valor de crear y compartir contenidos de valor alrededor de los datos, con el fin de iniciar la conversaci\u00f3n con sus audiencias, provocando su viralidad y complementando la historia de la compa\u00f1\u00eda con sus experiencias.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>\u00a0<strong>**Colaboraci\u00f3n basada en el art\u00edculo Data Driven Content: Ideas that Work in Content Marketing de Richard Braxter.<\/strong><\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","content-type":"","_ayudawp_aiss_exclude":false,"_ayudawp_aiss_exclude_summary":false,"_ayudawp_aiss_summary":"Adem\u00e1s de que, otra de sus funciones es alimentar y enriquecer sus Medios Propios (blogs, p\u00e1gina web, revistas internas, whitepapers, entre otros) con contenidos que agreguen valor a sus clientes actuales y potenciales, adem\u00e1s de capitalizarlos en su Relaci\u00f3n con Medios e Influenciadores Digitales y, la pregunta que surge es: \u00bfen qu\u00e9 momento me pongo a redactar los contenidos?. [\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" disabled_on=\"off|off|off\" _builder_version=\"4.27.4\" _module_preset=\"default\" background_color=\"rgba(168,30,100,0.31)\" background_enable_image=\"off\" background_size=\"initial\" background_position=\"top_left\" background_horizontal_offset=\"0%\" custom_margin=\"25px||50px||false|false\" custom_padding=\"0px||0px||true|false\" border_radii=\"on|25px|25px|25px|25px\" border_width_all=\"2px\" border_color_all=\"#0595a8\" box_shadow_style=\"preset4\" box_shadow_horizontal=\"0px\" box_shadow_color=\"#081116\" locked=\"off\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_row _builder_version=\"4.27.4\" _module_preset=\"default\" background_enable_color=\"off\" custom_margin=\"0px||0px||true|false\" custom_padding=\"5px||5px||true|false\" border_radii=\"on|25px|25px|25px|25px\" border_style_all=\"none\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_column type=\"4_4\" _builder_version=\"4.27.4\" _module_preset=\"default\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_text content_tablet=\". \" content_last_edited=\"on|desktop\" _builder_version=\"4.27.7\" _module_preset=\"default\" text_font=\"Oswald|700|||||||\" text_text_color=\"#3c4046\" text_font_size=\"25px\" ul_font=\"EditorialNew-Light|300|||||||\" ul_text_color=\"#000000\" ul_font_size=\"1.25rem\" ul_line_height=\"1.6em\" header_5_font=\"|||on|||||\" header_5_text_color=\"#081116\" header_5_font_size=\"1.4rem\" header_6_font=\"EditorialNew-Light||||||||\" header_6_text_color=\"#081116\" header_6_font_size=\"1.3rem\" header_6_line_height=\"1.3em\" background_enable_color=\"off\" background_image=\"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/sabias-que_.webp\" background_size=\"custom\" background_image_width=\"12%\" background_position=\"top_right\" background_horizontal_offset=\"4%\" background_vertical_offset=\"40%\" custom_padding=\"25px|200px|20px|50px|false|false\" custom_padding_tablet=\"25px|200px|20px|50px|false|false\" custom_padding_phone=\"60px|25px|10px|25px|false|true\" custom_padding_last_edited=\"on|phone\" hover_enabled=\"0\" background_last_edited=\"on|phone\" background_image_width_phone=\"27%\" background_horizontal_offset_phone=\"5%\" background_vertical_offset_phone=\"1%\" custom_css_main_element=\"ul {margin-top:25px;}\" border_radii=\"on|20px|20px|20px|20px\" box_shadow_style=\"preset3\" box_shadow_color=\"rgba(0,0,0,0.15)\" locked=\"off\" global_colors_info=\"{}\" custom_css_main_element_last_edited=\"on|phone\" custom_css_main_element_phone=\"background-position: right 4% top 0% !important;\" custom_css_main_element_tablet=\"ul {margin-top:25px;}\" theme_builder_area=\"post_content\" sticky_enabled=\"0\"]. 60% de los CMOs (Gerentes de Marketing) prev\u00e9n un incremento en los presupuestos en Marketing de Contenidos como resultado de un positivo ROI. Tambi\u00e9n te puede interesar:. [\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.27.6\" _module_preset=\"default\" background_enable_color=\"off\" custom_margin=\"0px||25px||false|false\" custom_padding=\"25px||0px||false|false\" locked=\"off\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_row use_custom_gutter=\"on\" gutter_width=\"1\" make_equal=\"on\" _builder_version=\"4.27.6\" _module_preset=\"default\" background_color=\"rgba(5,149,168,0.73)\" custom_margin=\"0px||0px||false|false\" custom_padding=\"16px|25px|1px|25px|false|true\" border_width_top=\"1px\" border_width_bottom=\"1px\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_column type=\"4_4\" _builder_version=\"4.27.6\" _module_preset=\"default\" custom_padding=\"0px||0px||false|false\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][dpdfg_filtergrid custom_query=\"posts_ids\" posts_ids=\"409\" post_number=\"1\" thumbnail_size=\"510x382\" use_overlay=\"off\" title_link=\"on\" show_post_meta=\"off\" read_more_window=\"on\" custom_content_container=\"off\" show_filters=\"off\" show_pagination=\"off\" items_layout=\"dp-dfg-layout-list\" thumb_min_width=\"36%\" thumb_width=\"36%\" column_gutter=\"0em\" row_gutter=\"0em\" items_skin=\"dp-dfg-skin-none\" primary_view=\"%91{%22name%22:%22thumbnail%22,%22show%22:%22on%22},{%22name%22:%22overlay%22,%22show%22:%22on%22},{%22name%22:%22title%22,%22show%22:%22off%22},{%22name%22:%22meta%22,%22show%22:%22off%22},{%22name%22:%22ext%22,%22show%22:%22off%22},{%22name%22:%22content%22,%22show%22:%22off%22},{%22name%22:%22read_more_button%22,%22show%22:%22off%22},{%22name%22:%22action_button%22,%22show%22:%22off%22},{%22name%22:%22custom_content%22,%22show%22:%22off%22}%93\" secondary_view=\"%91{%22name%22:%22thumbnail%22,%22show%22:%22off%22},{%22name%22:%22meta%22,%22show%22:%22on%22},{%22name%22:%22title%22,%22show%22:%22on%22},{%22name%22:%22ext%22,%22show%22:%22on%22},{%22name%22:%22content%22,%22show%22:%22on%22},{%22name%22:%22action_button%22,%22show%22:%22on%22},{%22name%22:%22read_more_button%22,%22show%22:%22on%22},{%22name%22:%22custom_content%22,%22show%22:%22on%22}%93\" bg_items=\"RGBA(255,255,255,0)\" _builder_version=\"4.27.7\" _module_preset=\"default\" dpdfg_entry_title_level=\"h6\" dpdfg_entry_title_font=\"Oswald|||on|||||\" dpdfg_entry_title_text_color=\"#506ebb\" dpdfg_entry_title_font_size=\"1.2rem\" dpdfg_entry_title_line_height=\"1.1em\" dpdfg_entry_summary_font=\"EditorialNew-Light||||||||\" dpdfg_entry_summary_text_color=\"#FFFFFF\" dpdfg_entry_summary_font_size=\"1.5rem\" dpdfg_entry_summary_line_height=\"1.2em\" background_enable_color=\"off\" custom_read_more_button=\"on\" read_more_button_text_color=\"#FFFFFF\" read_more_button_font=\"Oswald|||on|||||\" read_more_button_icon=\"&#x24;||divi||400\" read_more_button_on_hover=\"off\" read_more_button_alignment=\"center\" read_more_button_custom_margin=\"||0px||false|false\" read_more_button_custom_padding=\"||||false|false\" height=\"80px\" height_tablet=\"85px\" height_phone=\"125px\" height_last_edited=\"on|tablet\" custom_margin=\"0px|0px|0px|0px|false|false\" custom_padding=\"0px|0px|0px|0px|false|false\" hover_enabled=\"0\" dpdfg_entry_title_line_height_tablet=\"1.4em\" dpdfg_entry_title_line_height_phone=\"1.4em\" dpdfg_entry_title_line_height_last_edited=\"on|phone\" custom_css_entry-thumb=\"width: 120px;||height: auto;\" custom_css_entry-header=\"margin-left: -210px;||padding-top: 12px;\" border_radii=\"off||||\" border_color_all=\"#000000\" border_width_top=\"2px\" border_width_bottom=\"2px\" global_colors_info=\"{}\" custom_css_entry-header_last_edited=\"on|tablet\" custom_css_entry-header_phone=\"margin-left: 130px;||padding-top: 0px;||margin-top: -80px;||width:63%;\" custom_css_entry-header_tablet=\"margin-left: -170px;||padding-top: 0px;\" theme_builder_area=\"post_content\" sticky_enabled=\"0\"][\/dpdfg_filtergrid][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\"1\" _builder_version=\"4.16\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"][et_pb_row _builder_version=\"4.27.7\" background_size=\"initial\" background_position=\"top_left\" background_repeat=\"repeat\" hover_enabled=\"0\" global_colors_info=\"{}\" theme_builder_area=\"post_content\" custom_padding=\"0px||0px||true|false\" sticky_enabled=\"0\"][et_pb_column type=\"4_4\" _builder_version=\"4.16\" custom_padding=\"|||\" global_colors_info=\"{}\" custom_padding__hover=\"|||\" theme_builder_area=\"post_content\"][et_pb_text _builder_version=\"4.27.4\" background_size=\"initial\" background_position=\"top_left\" background_repeat=\"repeat\" global_colors_info=\"{}\" theme_builder_area=\"post_content\"].","_ayudawp_aiss_summary_provider":"extractive","_ayudawp_aiss_summary_hash":"5a9a5ed35bfa3ebd4309cc268939ecb85bf06d15","_joinchat":[],"footnotes":""},"categories":[33],"tags":[772,773,774,2905],"class_list":["post-2897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-de-contenido","tag-creacion-de-contenidos-cautivantes","tag-contenidos-impulsados-por-datos","tag-beneficios-de-una-agencia-de-contenidos","tag-articulos","et-has-post-format-content","et_post_format-et-post-format-standard"],"a3_pvc":{"activated":false,"total_views":2316,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Agencias de Contenidos Impulsados por Datos \u00bfPor qu\u00e9 acudir a ellas? - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Agencias de Contenidos Impulsados por Datos \u00bfPor qu\u00e9 acudir a ellas? - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones\" \/>\n<meta property=\"og:description\" content=\"A lo largo de mi caminar como consultor en Relaciones P\u00fablicas, me ha tocado ver el d\u00eda a d\u00eda de mis contactos de Marketing y Comunicaci\u00f3n (MARCOM), los cuales adem\u00e1s de coordinar las actividades de RP; tienen que realizar investigaciones de mercado, eventos, coordinar a las agencias de Publicidad, Dise\u00f1o y Redes Sociales, as\u00ed como [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/\" \/>\n<meta property=\"og:site_name\" content=\"Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/infosol\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-16T21:16:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-16T17:39:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/contenidos-impulsados-por-datos.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Equipo Consultor InfoSol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EspacioInfoSol\" \/>\n<meta name=\"twitter:site\" content=\"@EspacioInfoSol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo Consultor InfoSol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/\"},\"author\":{\"name\":\"Equipo Consultor InfoSol\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#\\\/schema\\\/person\\\/3c6cce488f0157396736bfb13ab1bb9e\"},\"headline\":\"Agencias de Contenidos Impulsados por Datos \u00bfPor qu\u00e9 acudir a ellas?\",\"datePublished\":\"2016-06-16T21:16:34+00:00\",\"dateModified\":\"2026-07-16T17:39:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/\"},\"wordCount\":2285,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/contenidos-impulsados-por-datos.webp\",\"keywords\":[\"creaci\u00f3n de contenidos cautivantes\",\"contenidos impulsados por datos\",\"beneficios de una agencia de contenidos\",\"Art\u00edculos\"],\"articleSection\":[\"Marketing de Contenidos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/\",\"name\":\"Agencias de Contenidos Impulsados por Datos \u00bfPor qu\u00e9 acudir a ellas? - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/contenidos-impulsados-por-datos.webp\",\"datePublished\":\"2016-06-16T21:16:34+00:00\",\"dateModified\":\"2026-07-16T17:39:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/contenidos-impulsados-por-datos.webp\",\"contentUrl\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/contenidos-impulsados-por-datos.webp\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marketing de Contenidos\",\"item\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/category\\\/marketing-de-contenido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Agencias de Contenidos Impulsados por Datos \u00bfPor qu\u00e9 acudir a ellas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/\",\"name\":\"Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones\",\"description\":\"Comunicaci\u00f3n, Relaciones P\u00fablicas, Redes Sociales y algo m\u00e1s...\",\"publisher\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#organization\",\"name\":\"InfoSol\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/InfoSol-6.0-160x46-1.webp\",\"contentUrl\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/InfoSol-6.0-160x46-1.webp\",\"width\":160,\"height\":46,\"caption\":\"InfoSol\"},\"image\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infosol\\\/\",\"https:\\\/\\\/x.com\\\/EspacioInfoSol\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/grupoinfosol\\\/\",\"https:\\\/\\\/www.pinterest.com.mx\\\/GrupoInfoSol\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/InfoSolMiEspacio\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#\\\/schema\\\/person\\\/3c6cce488f0157396736bfb13ab1bb9e\",\"name\":\"Equipo Consultor InfoSol\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/cropped-virgula-200x200-1-96x96.webp\",\"url\":\"http:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/cropped-virgula-200x200-1-96x96.webp\",\"contentUrl\":\"http:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/cropped-virgula-200x200-1-96x96.webp\",\"caption\":\"Equipo Consultor InfoSol\"},\"description\":\"El equipo gerencial de InfoSol est\u00e1 compuesto por expertos en la industria, que aportan a\u00f1os de experiencia a una empresa en constante evoluci\u00f3n.\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/author\\\/e-infosol\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Agencias de Contenidos Impulsados por Datos \u00bfPor qu\u00e9 acudir a ellas? - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/","og_locale":"es_ES","og_type":"article","og_title":"Agencias de Contenidos Impulsados por Datos \u00bfPor qu\u00e9 acudir a ellas? - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","og_description":"A lo largo de mi caminar como consultor en Relaciones P\u00fablicas, me ha tocado ver el d\u00eda a d\u00eda de mis contactos de Marketing y Comunicaci\u00f3n (MARCOM), los cuales adem\u00e1s de coordinar las actividades de RP; tienen que realizar investigaciones de mercado, eventos, coordinar a las agencias de Publicidad, Dise\u00f1o y Redes Sociales, as\u00ed como [&hellip;]","og_url":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/","og_site_name":"Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","article_publisher":"https:\/\/www.facebook.com\/infosol\/","article_published_time":"2016-06-16T21:16:34+00:00","article_modified_time":"2026-07-16T17:39:53+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/contenidos-impulsados-por-datos.webp","type":"image\/webp"}],"author":"Equipo Consultor InfoSol","twitter_card":"summary_large_image","twitter_creator":"@EspacioInfoSol","twitter_site":"@EspacioInfoSol","twitter_misc":{"Escrito por":"Equipo Consultor InfoSol","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/#article","isPartOf":{"@id":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/"},"author":{"name":"Equipo Consultor InfoSol","@id":"https:\/\/infosol.com.mx\/wordpress\/#\/schema\/person\/3c6cce488f0157396736bfb13ab1bb9e"},"headline":"Agencias de Contenidos Impulsados por Datos \u00bfPor qu\u00e9 acudir a ellas?","datePublished":"2016-06-16T21:16:34+00:00","dateModified":"2026-07-16T17:39:53+00:00","mainEntityOfPage":{"@id":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/"},"wordCount":2285,"commentCount":0,"publisher":{"@id":"https:\/\/infosol.com.mx\/wordpress\/#organization"},"image":{"@id":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/#primaryimage"},"thumbnailUrl":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/contenidos-impulsados-por-datos.webp","keywords":["creaci\u00f3n de contenidos cautivantes","contenidos impulsados por datos","beneficios de una agencia de contenidos","Art\u00edculos"],"articleSection":["Marketing de Contenidos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/","url":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/","name":"Agencias de Contenidos Impulsados por Datos \u00bfPor qu\u00e9 acudir a ellas? - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","isPartOf":{"@id":"https:\/\/infosol.com.mx\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/#primaryimage"},"image":{"@id":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/#primaryimage"},"thumbnailUrl":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/contenidos-impulsados-por-datos.webp","datePublished":"2016-06-16T21:16:34+00:00","dateModified":"2026-07-16T17:39:53+00:00","breadcrumb":{"@id":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/#primaryimage","url":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/contenidos-impulsados-por-datos.webp","contentUrl":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/contenidos-impulsados-por-datos.webp","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/infosol.com.mx\/wordpress\/agencias-de-contenidos-impulsados-por-datos-por-que-acudir-a-ellas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/infosol.com.mx\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Marketing de Contenidos","item":"https:\/\/infosol.com.mx\/wordpress\/category\/marketing-de-contenido\/"},{"@type":"ListItem","position":3,"name":"Agencias de Contenidos Impulsados por Datos \u00bfPor qu\u00e9 acudir a ellas?"}]},{"@type":"WebSite","@id":"https:\/\/infosol.com.mx\/wordpress\/#website","url":"https:\/\/infosol.com.mx\/wordpress\/","name":"Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","description":"Comunicaci\u00f3n, Relaciones P\u00fablicas, Redes Sociales y algo m\u00e1s...","publisher":{"@id":"https:\/\/infosol.com.mx\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infosol.com.mx\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infosol.com.mx\/wordpress\/#organization","name":"InfoSol","url":"https:\/\/infosol.com.mx\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infosol.com.mx\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/InfoSol-6.0-160x46-1.webp","contentUrl":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/InfoSol-6.0-160x46-1.webp","width":160,"height":46,"caption":"InfoSol"},"image":{"@id":"https:\/\/infosol.com.mx\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infosol\/","https:\/\/x.com\/EspacioInfoSol","https:\/\/www.linkedin.com\/company\/grupoinfosol\/","https:\/\/www.pinterest.com.mx\/GrupoInfoSol\/","https:\/\/www.youtube.com\/user\/InfoSolMiEspacio"]},{"@type":"Person","@id":"https:\/\/infosol.com.mx\/wordpress\/#\/schema\/person\/3c6cce488f0157396736bfb13ab1bb9e","name":"Equipo Consultor InfoSol","image":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/cropped-virgula-200x200-1-96x96.webp","url":"http:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/cropped-virgula-200x200-1-96x96.webp","contentUrl":"http:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/cropped-virgula-200x200-1-96x96.webp","caption":"Equipo Consultor InfoSol"},"description":"El equipo gerencial de InfoSol est\u00e1 compuesto por expertos en la industria, que aportan a\u00f1os de experiencia a una empresa en constante evoluci\u00f3n.","url":"https:\/\/infosol.com.mx\/wordpress\/author\/e-infosol\/"}]}},"_links":{"self":[{"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/posts\/2897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/comments?post=2897"}],"version-history":[{"count":21,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/posts\/2897\/revisions"}],"predecessor-version":[{"id":244612,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/posts\/2897\/revisions\/244612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/media\/18234"}],"wp:attachment":[{"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/media?parent=2897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/categories?post=2897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/tags?post=2897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}