{"id":20255,"date":"2024-04-22T09:15:00","date_gmt":"2024-04-22T15:15:00","guid":{"rendered":"https:\/\/infosol.com.mx\/wordpress\/?p=20255"},"modified":"2025-07-28T11:36:49","modified_gmt":"2025-07-28T17:36:49","slug":"transforma-tu-marketing-de-contenidos-con-el-periodismo","status":"publish","type":"post","link":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/","title":{"rendered":"Transforma tu marketing de contenidos con el periodismo"},"content":{"rendered":"\n<p>En mis recientes vacaciones, mientras disfrutaba de un caf\u00e9 en el centro de Tampico, tuve un encuentro imprevisto pero muy prometedor con Sara, una periodista local. La conversaci\u00f3n se dio mientras revisaba mi tel\u00e9fono buscando ideas frescas para mi siguiente contenido sobre liderazgo; y es que generar piezas promocionales que tambi\u00e9n conecten emocionalmente con la audiencia, puede volverse todo un reto especialmente en el \u00e1mbito del <strong>marketing de contenidos<\/strong>.<\/p>\n\n<p>Esa ma\u00f1ana, Sara repasaba sus notas, exploraba tem\u00e1ticas y revisaba informaci\u00f3n que la ayudara a desarrollar historias interesantes y, como ella me lo dir\u00eda, \u201cque marcaran la diferencia en la vida de sus lectores\u201d. Durante nuestra charla, descubrimos que, aunque hay campos de especializaci\u00f3n diferentes, compartimos un objetivo com\u00fan: cautivar y comprometer a la audiencia. Eso me dej\u00f3 muy en claro que, al combinar las habilidades y conocimientos del periodismo con los de <strong>liderazgo y marketing<\/strong>, es posible crear contenidos que informen e inspiren a las audiencias.<\/p>\n\n<p>En la <strong>industria del marketing<\/strong>, el contenido es uno de los temas de los que m\u00e1s se habla. Las marcas entienden que necesitan dedicar tiempo y recursos a sus esfuerzos de\u00a0<a href=\"https:\/\/infosol.com.mx\/wordpress\/domina-el-marketing-de-contenidos-para-relaciones-publicas-digitales\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>marketing de contenidos<\/strong><\/a>\u00a0para mantenerse por delante de la competencia y seguir siendo relevantes para el mercado. Pero a medida que el\u00a0<strong>marketing de contenidos<\/strong>\u00a0evoluciona, los profesionales en marketing deben buscar nuevas formas de destacarse y mantener el flujo de contenido.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>C\u00f3mo crear marketing de contenidos inspir\u00e1ndose en el periodismo<\/strong><\/h2>\n\n<p>Una manera efectiva de crear contenidos es tomando inspiraci\u00f3n directamente del periodismo. Al igual que Sara busca tem\u00e1ticas interesantes y revisa informaci\u00f3n relevante para sus historias, los profesionales en <strong>marketing <\/strong>podemos adoptar un enfoque similar al desarrollar <strong>contenido de marca<\/strong>. Esto implica investigar tendencias, analizar datos y comprender las necesidades y deseos de la audiencia para crear narrativas genuinas que transmitan valores, cuenten experiencias y ofrezcan soluciones a los problemas del p\u00fablico.<\/p>\n\n<p>Los principios fundamentales que gu\u00edan el trabajo period\u00edstico son, en esencia, los mismos que pueden impulsar el \u00e9xito de nuestra\u00a0<a href=\"https:\/\/soy.marketing\/asi-puedes-mejorar-tu-estrategia-de-marketing-de-contenidos\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>estrategia de marketing de contenidos<\/strong><\/a>. \u00bfC\u00f3mo lograrlo? Aqu\u00ed te comparto algunas ideas que, desde mi punto de vista, podemos retomar y aprender del periodismo para crear piezas de contenido m\u00e1s atractivas y relevantes.<\/p>\n\n<p><strong>Investigaci\u00f3n exhaustiva:\u00a0<\/strong>El periodismo se basa en la investigaci\u00f3n meticulosa y la verificaci\u00f3n de los hechos para mantener su integridad y credibilidad. Del mismo modo, las marcas que deseen destacarse en un mercado saturado de contenidos deben priorizar la precisi\u00f3n y la calidad de la informaci\u00f3n que comparten. Esto es esencial para darle valor al contenido.<\/p>\n\n<p><strong>Credibilidad:<\/strong>\u00a0Es una moneda invaluable en el mundo del <strong>marketing de contenidos<\/strong> y una de las principales ventajas que ofrece el periodismo. Si tomamos en cuenta que los consumidores son cada vez m\u00e1s exigentes y esc\u00e9pticos ante los mensajes publicitarios, la creaci\u00f3n de contenido con informaci\u00f3n precisa, confiable y fundamentada en datos permitir\u00e1 ganar la confianza de la audiencia de una manera aut\u00e9ntica y duradera, ayudando a establecer relaciones s\u00f3lidas y significativas.<\/p>\n\n<p><strong>Relevancia y oportunidad:\u00a0<\/strong>Los periodistas est\u00e1s constantemente atentos a lo que est\u00e1 sucediendo en el mundo y buscan profundizar en temas relevantes para su audiencia, y abordarlos desde una perspectiva informativa y educativa. Las marcas pueden seguir este ejemplo al mantenerse al d\u00eda con las tendencias y los acontecimientos actuales que son relevantes para su industria y su audiencia. Estas caracter\u00edsticas dan valor al contenido, y permiten a las marcas posicionarse como autoridades en su sector.<\/p>\n\n<p><strong>Colaboraci\u00f3n y\u00a0<em>networking<\/em>:\u00a0<\/strong>El periodismo a menudo implica colaboraciones entre diferentes profesionales, desde reporteros hasta editores y fot\u00f3grafos. Del mismo modo, las marcas pueden beneficiarse al colaborar con creadores de contenido, influenciadores digitales y otros socios estrat\u00e9gicos para amplificar su mensaje y llegar a nuevas audiencias. Al construir relaciones s\u00f3lidas en el ecosistema digital, pueden expandir su alcance y fortalecer su\u00a0<em>engagement<\/em>.<\/p>\n\n<p><strong>Narrativa cautivadora y humanizada:\u00a0<\/strong>Una historia bien contada tiene el poder de cautivar a la audiencia y crear una conexi\u00f3n emocional duradera. La labor period\u00edstica comprende esto a la perfecci\u00f3n, y las marcas tambi\u00e9n deber\u00edan hacerlo. En lugar de simplemente promocionar productos o servicios, a trav\u00e9s de sus contenidos, pueden aprovechar el poder de la narrativa humanizada para\u00a0<a href=\"https:\/\/infosol.com.mx\/wordpress\/storytelling-por-que-las-marcas-necesitan-contar-historias\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>contar historias que resuenen con su audiencia<\/strong><\/a>, y las ayuden a establecer relaciones m\u00e1s profundas.<\/p>\n\n<p><strong>Objetividad e imparcialidad:<\/strong>\u00a0Aunque los profesionales de marketing tenemos un inter\u00e9s comercial en promover a las marcas, adoptar un enfoque objetivo y equilibrado en nuestro contenido puede ayudar a ganar la confianza de la audiencia. Evitemos la parcialidad excesiva y presentemos informaci\u00f3n de manera imparcial para fortalecer la credibilidad de la marca.<\/p>\n\n<p><strong>Diversidad de formatos y canales:\u00a0<\/strong>No es ning\u00fan secreto que el periodismo se ha adaptado a los cambios tecnol\u00f3gicos al diversificar sus formatos y canales de distribuci\u00f3n. Las marcas necesitan aprender de esta versatilidad al experimentar con una variedad de formatos de contenido, como videos, infograf\u00edas, podcasts y m\u00e1s. Adem\u00e1s, al distribuir su contenido a trav\u00e9s de m\u00faltiples canales, estas pueden amplificar su alcance y llegar a audiencias diversas y dispersas.<\/p>\n\n<p><strong>\u00c9nfasis en la \u00e9tica y la integridad:\u00a0<\/strong>Los periodistas siguen un c\u00f3digo \u00e9tico que incluye principios como la honestidad, la transparencia y el respeto por la privacidad. Los profesionales de marketing podemos beneficiarnos al adherirnos a principios similares en la creaci\u00f3n y distribuci\u00f3n de contenido, esto generar\u00e1 confianza y ayudar\u00e1 a construir relaciones duraderas con la audiencia.<\/p>\n\n<p>Estas ideas son apenas una muestra de c\u00f3mo los profesionales del marketing podemos potenciar notablemente la eficacia de nuestra estrategia de contenido, tomando prestados conceptos del periodismo que nos ayudar\u00e1n a generar un impacto m\u00e1s profundo y positivo en la audiencia. La clave radica en comprender que, al final del d\u00eda, se trata de contar historias que resuenen con las personas y las inspiren a actuar.<\/p>\n\n<p>Si bien el contenido sigue siendo un elemento fundamental en los esfuerzos de marketing, tambi\u00e9n es crucial innovar constantemente para mantenerse relevante. Al combinar las habilidades y conocimientos del periodismo con los del liderazgo y el marketing, podemos crear contenido que destaque, inspire y conecte emocionalmente con nuestra audiencia, marcando as\u00ed la diferencia en el mundo del marketing de contenidos.<\/p>\n\n<p>\u00a0Este contenido apareci\u00f3 por primera vez en <a href=\"https:\/\/soy.marketing\/tendencias-de-relaciones-publicas-estamos-listos-para-2024\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Soy Marketing<\/strong><\/a>.<\/p>\n\n<p>Conoce m\u00e1s contenido del autor en <a href=\"https:\/\/soy.marketing\/columnista\/hector-meza\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Soy Marketing<\/strong><\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conoce c\u00f3mo crear marketing de contenidos tomando inspiraci\u00f3n directamente del periodismo.<\/p>\n","protected":false},"author":2,"featured_media":20270,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","_ayudawp_aiss_exclude":false,"_joinchat":[],"footnotes":""},"categories":[33],"tags":[638,1187,2648,2905],"class_list":["post-20255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-de-contenido","tag-como-crear-marketing-de-contenidos","tag-estrategia-de-marketing-de-contenidos","tag-marketing-de-contenidos-periodismo","tag-articulos"],"a3_pvc":{"activated":false,"total_views":900,"today_views":1},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transforma tu marketing de contenidos con el periodismo - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transforma tu marketing de contenidos con el periodismo - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones\" \/>\n<meta property=\"og:description\" content=\"Conoce c\u00f3mo crear marketing de contenidos tomando inspiraci\u00f3n directamente del periodismo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/infosol\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/HectorM.MezaC?ref=br_rs_WyJrZXl3b3Jkc191c2VycyJd\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-22T15:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-28T17:36:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/transforma-tu-marketing-de-contenidos-con-el-periodismo-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"H\u00e9ctor M. Meza\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/HectorMezaC\" \/>\n<meta name=\"twitter:site\" content=\"@EspacioInfoSol\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"H\u00e9ctor M. Meza\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/\"},\"author\":{\"name\":\"H\u00e9ctor M. Meza\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#\\\/schema\\\/person\\\/bb70f136abbd7e36b1f997a14c53ac3a\"},\"headline\":\"Transforma tu marketing de contenidos con el periodismo\",\"datePublished\":\"2024-04-22T15:15:00+00:00\",\"dateModified\":\"2025-07-28T17:36:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/\"},\"wordCount\":1097,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo-1.webp\",\"keywords\":[\"c\u00f3mo crear marketing de contenidos\",\"estrategia de marketing de contenidos\",\"Marketing de contenidos periodismo\",\"Art\u00edculos\"],\"articleSection\":[\"Marketing de Contenidos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/\",\"name\":\"Transforma tu marketing de contenidos con el periodismo - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo-1.webp\",\"datePublished\":\"2024-04-22T15:15:00+00:00\",\"dateModified\":\"2025-07-28T17:36:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo-1.webp\",\"contentUrl\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo-1.webp\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/transforma-tu-marketing-de-contenidos-con-el-periodismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marketing de Contenidos\",\"item\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/category\\\/marketing-de-contenido\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Transforma tu marketing de contenidos con el periodismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/\",\"name\":\"Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones\",\"description\":\"Comunicaci\u00f3n, Relaciones P\u00fablicas, Redes Sociales y algo m\u00e1s...\",\"publisher\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#organization\",\"name\":\"InfoSol\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/InfoSol-6.0-160x46-1.webp\",\"contentUrl\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/InfoSol-6.0-160x46-1.webp\",\"width\":160,\"height\":46,\"caption\":\"InfoSol\"},\"image\":{\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/infosol\\\/\",\"https:\\\/\\\/x.com\\\/EspacioInfoSol\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/grupoinfosol\\\/\",\"https:\\\/\\\/www.pinterest.com.mx\\\/GrupoInfoSol\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/InfoSolMiEspacio\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/#\\\/schema\\\/person\\\/bb70f136abbd7e36b1f997a14c53ac3a\",\"name\":\"H\u00e9ctor M. Meza\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"http:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/cropped-h-meza-96x96.png\",\"url\":\"http:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/cropped-h-meza-96x96.png\",\"contentUrl\":\"http:\\\/\\\/infosol.com.mx\\\/wordpress\\\/wp-content\\\/uploads\\\/cropped-h-meza-96x96.png\",\"caption\":\"H\u00e9ctor M. Meza\"},\"description\":\"Director General de InfoSol. MBA, Consultor y Catedr\u00e1tico en Estrategias de Comunicaci\u00f3n Integradas a la Mercadotecnia. Fue Vicepresidente en IBM de M\u00e9xico y Presidente de Motorola para M\u00e9xico, Centroam\u00e9rica y el Caribe y VP de la Corporaci\u00f3n.\",\"sameAs\":[\"http:\\\/\\\/www.infosol.com.mx\",\"https:\\\/\\\/www.facebook.com\\\/HectorM.MezaC?ref=br_rs_WyJrZXl3b3Jkc191c2VycyJd\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/h\u00e9ctor-meza-curiel\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/HectorMezaC\"],\"url\":\"https:\\\/\\\/infosol.com.mx\\\/wordpress\\\/author\\\/h-meza\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transforma tu marketing de contenidos con el periodismo - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/","og_locale":"es_ES","og_type":"article","og_title":"Transforma tu marketing de contenidos con el periodismo - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","og_description":"Conoce c\u00f3mo crear marketing de contenidos tomando inspiraci\u00f3n directamente del periodismo.","og_url":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/","og_site_name":"Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","article_publisher":"https:\/\/www.facebook.com\/infosol\/","article_author":"https:\/\/www.facebook.com\/HectorM.MezaC?ref=br_rs_WyJrZXl3b3Jkc191c2VycyJd","article_published_time":"2024-04-22T15:15:00+00:00","article_modified_time":"2025-07-28T17:36:49+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/transforma-tu-marketing-de-contenidos-con-el-periodismo-1.webp","type":"image\/webp"}],"author":"H\u00e9ctor M. Meza","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/HectorMezaC","twitter_site":"@EspacioInfoSol","twitter_misc":{"Escrito por":"H\u00e9ctor M. Meza","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/#article","isPartOf":{"@id":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/"},"author":{"name":"H\u00e9ctor M. Meza","@id":"https:\/\/infosol.com.mx\/wordpress\/#\/schema\/person\/bb70f136abbd7e36b1f997a14c53ac3a"},"headline":"Transforma tu marketing de contenidos con el periodismo","datePublished":"2024-04-22T15:15:00+00:00","dateModified":"2025-07-28T17:36:49+00:00","mainEntityOfPage":{"@id":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/"},"wordCount":1097,"commentCount":0,"publisher":{"@id":"https:\/\/infosol.com.mx\/wordpress\/#organization"},"image":{"@id":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/#primaryimage"},"thumbnailUrl":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/transforma-tu-marketing-de-contenidos-con-el-periodismo-1.webp","keywords":["c\u00f3mo crear marketing de contenidos","estrategia de marketing de contenidos","Marketing de contenidos periodismo","Art\u00edculos"],"articleSection":["Marketing de Contenidos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/","url":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/","name":"Transforma tu marketing de contenidos con el periodismo - Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","isPartOf":{"@id":"https:\/\/infosol.com.mx\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/#primaryimage"},"image":{"@id":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/#primaryimage"},"thumbnailUrl":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/transforma-tu-marketing-de-contenidos-con-el-periodismo-1.webp","datePublished":"2024-04-22T15:15:00+00:00","dateModified":"2025-07-28T17:36:49+00:00","breadcrumb":{"@id":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/#primaryimage","url":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/transforma-tu-marketing-de-contenidos-con-el-periodismo-1.webp","contentUrl":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/transforma-tu-marketing-de-contenidos-con-el-periodismo-1.webp","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/infosol.com.mx\/wordpress\/transforma-tu-marketing-de-contenidos-con-el-periodismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/infosol.com.mx\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Marketing de Contenidos","item":"https:\/\/infosol.com.mx\/wordpress\/category\/marketing-de-contenido\/"},{"@type":"ListItem","position":3,"name":"Transforma tu marketing de contenidos con el periodismo"}]},{"@type":"WebSite","@id":"https:\/\/infosol.com.mx\/wordpress\/#website","url":"https:\/\/infosol.com.mx\/wordpress\/","name":"Charlas de Caf\u00e9 de Comunicaci\u00f3n y Otras Pasiones","description":"Comunicaci\u00f3n, Relaciones P\u00fablicas, Redes Sociales y algo m\u00e1s...","publisher":{"@id":"https:\/\/infosol.com.mx\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/infosol.com.mx\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/infosol.com.mx\/wordpress\/#organization","name":"InfoSol","url":"https:\/\/infosol.com.mx\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/infosol.com.mx\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/InfoSol-6.0-160x46-1.webp","contentUrl":"https:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/InfoSol-6.0-160x46-1.webp","width":160,"height":46,"caption":"InfoSol"},"image":{"@id":"https:\/\/infosol.com.mx\/wordpress\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/infosol\/","https:\/\/x.com\/EspacioInfoSol","https:\/\/www.linkedin.com\/company\/grupoinfosol\/","https:\/\/www.pinterest.com.mx\/GrupoInfoSol\/","https:\/\/www.youtube.com\/user\/InfoSolMiEspacio"]},{"@type":"Person","@id":"https:\/\/infosol.com.mx\/wordpress\/#\/schema\/person\/bb70f136abbd7e36b1f997a14c53ac3a","name":"H\u00e9ctor M. Meza","image":{"@type":"ImageObject","inLanguage":"es","@id":"http:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/cropped-h-meza-96x96.png","url":"http:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/cropped-h-meza-96x96.png","contentUrl":"http:\/\/infosol.com.mx\/wordpress\/wp-content\/uploads\/cropped-h-meza-96x96.png","caption":"H\u00e9ctor M. Meza"},"description":"Director General de InfoSol. MBA, Consultor y Catedr\u00e1tico en Estrategias de Comunicaci\u00f3n Integradas a la Mercadotecnia. Fue Vicepresidente en IBM de M\u00e9xico y Presidente de Motorola para M\u00e9xico, Centroam\u00e9rica y el Caribe y VP de la Corporaci\u00f3n.","sameAs":["http:\/\/www.infosol.com.mx","https:\/\/www.facebook.com\/HectorM.MezaC?ref=br_rs_WyJrZXl3b3Jkc191c2VycyJd","https:\/\/www.linkedin.com\/in\/h\u00e9ctor-meza-curiel\/","https:\/\/x.com\/https:\/\/twitter.com\/HectorMezaC"],"url":"https:\/\/infosol.com.mx\/wordpress\/author\/h-meza\/"}]}},"_links":{"self":[{"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/posts\/20255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/comments?post=20255"}],"version-history":[{"count":13,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/posts\/20255\/revisions"}],"predecessor-version":[{"id":24612,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/posts\/20255\/revisions\/24612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/media\/20270"}],"wp:attachment":[{"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/media?parent=20255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/categories?post=20255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/infosol.com.mx\/wordpress\/wp-json\/wp\/v2\/tags?post=20255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}